{"id":3114,"date":"2026-05-22T10:54:25","date_gmt":"2026-05-22T16:54:25","guid":{"rendered":"https:\/\/pulsociudadano.network\/?p=3114"},"modified":"2026-05-22T10:54:26","modified_gmt":"2026-05-22T16:54:26","slug":"ale-rojo-de-la-vega-recibe-a-sarah-duffy-consul-general-de-eu-para-coordinar-acciones-rumbo-al-mundial-2026","status":"publish","type":"post","link":"https:\/\/pulsociudadano.network\/index.php\/2026\/05\/22\/ale-rojo-de-la-vega-recibe-a-sarah-duffy-consul-general-de-eu-para-coordinar-acciones-rumbo-al-mundial-2026\/","title":{"rendered":"ALE ROJO DE LA VEGA RECIBE A SARAH DUFFY, C\u00d3NSUL GENERAL DE EU, PARA COORDINAR ACCIONES RUMBO AL MUNDIAL 2026"},"content":{"rendered":"<br \/><br \/>_* La alcaldesa recibi\u00f3 a la representante diplom\u00e1tica de Estados Unidos para dialogar sobre seguridad, turismo y atenci\u00f3n a visitantes._<br \/>_* Cuauht\u00e9moc concentra una parte fundamental de la actividad hotelera, gastron\u00f3mica y tur\u00edstica de la capital._<br \/><br \/><br \/>La alcaldesa Alessandra Rojo de la Vega sostuvo una reuni\u00f3n de trabajo con la c\u00f3nsul general de la Embajada de los Estados Unidos de Am\u00e9rica en M\u00e9xico, Sarah Duffy y su equipo diplom\u00e1tico, para fortalecer la coordinaci\u00f3n institucional rumbo al Mundial 2026 y dialogar sobre temas relacionados con seguridad, turismo y atenci\u00f3n a visitantes internacionales en la Ciudad de M\u00e9xico.<br \/><br \/>Durante el encuentro, realizado en la sede de la Alcald\u00eda Cuauht\u00e9moc, la alcaldesa destac\u00f3 que la demarcaci\u00f3n ser\u00e1 uno de los principales puntos de recepci\u00f3n de turismo nacional e internacional durante la Copa Mundial de la FIFA 2026, debido a su infraestructura hotelera, actividad econ\u00f3mica y oferta cultural y gastron\u00f3mica.<br \/><br \/>\u201cCuauht\u00e9moc ser\u00e1 la ventana de M\u00e9xico ante el mundo. Aqu\u00ed van a dormir, pasear, comer y convivir miles de visitantes, por eso estamos trabajando para recibirlos con una alcald\u00eda m\u00e1s ordenada, m\u00e1s segura y con mejores espacios p\u00fablicos\u201d, expres\u00f3.<br \/><br \/>Por su parte, la c\u00f3nsul Sarah Duffy destac\u00f3 la importancia de mantener coordinaci\u00f3n permanente con autoridades locales ante la presencia cotidiana de ciudadanos estadounidenses en la Ciudad de M\u00e9xico y particularmente en la Cuauht\u00e9moc.<br \/><br \/>La alcaldesa se\u00f1al\u00f3 que la demarcaci\u00f3n concentra el corredor gastron\u00f3mico m\u00e1s importante de Am\u00e9rica Latina, m\u00e1s de 66 mil unidades econ\u00f3micas y 39 mercados p\u00fablicos con alrededor de 15 mil locatarios, adem\u00e1s de ser la segunda zona con mayor n\u00famero de cuartos de hotel en el pa\u00eds.<br \/><br \/>Ale Rojo de la Vega explic\u00f3 que, rumbo al Mundial, la alcald\u00eda mantiene coordinaci\u00f3n permanente con autoridades capitalinas y federales para fortalecer acciones preventivas y operativos en zonas de alta afluencia como Roma, Condesa y Ju\u00e1rez.<br \/><br \/>Como parte de este trabajo, destac\u00f3 acciones de recuperaci\u00f3n de espacio p\u00fablico, iluminaci\u00f3n, videovigilancia y atenci\u00f3n territorial, mismas que han propiciado que Cuauht\u00e9moc sea la alcald\u00eda que m\u00e1s ha incrementado la percepci\u00f3n de seguridad en la capital.<br \/><br \/>Durante el encuentro, funcionarios de ambas representaciones intercambiaron informaci\u00f3n sobre las acciones que desempe\u00f1an en sus respectivos \u00e1mbitos de atenci\u00f3n y acordaron concretar reuniones posteriores para abordar temas espec\u00edficos, principalmente los relacionados con la presencia de ciudadanos estadounidenses en el Coraz\u00f3n de M\u00e9xico durante la Copa Mundial de la FIFA 2026, que se celebrar\u00e1 del 11 de junio al 19 de julio y tendr\u00e1 cinco partidos en el Estadio Ciudad de M\u00e9xico, incluido el inaugural.<br \/><br \/>La alcaldesa reiter\u00f3 que su gobierno mantendr\u00e1 colaboraci\u00f3n con distintos sectores e instituciones para fortalecer la atenci\u00f3n a vecinas, vecinos y visitantes.<br \/><br \/>\u201cCuando se trata de seguridad de las familias no existen colores partidistas ni intereses pol\u00edticos. Lo importante es construir mejores condiciones para quienes viven y visitan esta ciudad\u201d, concluy\u00f3.","protected":false},"excerpt":{"rendered":"<p>_* La alcaldesa recibi\u00f3 a la representante diplom\u00e1tica de Estados Unidos para dialogar sobre seguridad, turismo y atenci\u00f3n a visitantes.__* Cuauht\u00e9moc concentra una parte fundamental de la actividad hotelera, gastron\u00f3mica y tur\u00edstica de la capital._ La alcaldesa Alessandra Rojo de la Vega sostuvo una reuni\u00f3n de trabajo con la c\u00f3nsul general de la Embajada de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"ppma_author":[43],"class_list":["post-3114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"authors":[{"term_id":43,"user_id":6,"is_guest":0,"slug":"staff","display_name":"STAFF","avatar_url":{"url":"https:\/\/pulsociudadano.network\/wp-content\/uploads\/2023\/11\/cropped-301392363_529368922396272_1685931149298827625_n-1.jpg","url2x":"https:\/\/pulsociudadano.network\/wp-content\/uploads\/2023\/11\/cropped-301392363_529368922396272_1685931149298827625_n-1.jpg"},"author_category":"1","user_url":"","last_name":"Arrieta","first_name":"STAFF","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/posts\/3114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/comments?post=3114"}],"version-history":[{"count":1,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/posts\/3114\/revisions"}],"predecessor-version":[{"id":3117,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/posts\/3114\/revisions\/3117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/media\/3119"}],"wp:attachment":[{"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/media?parent=3114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/categories?post=3114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/tags?post=3114"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/pulsociudadano.network\/index.php\/wp-json\/wp\/v2\/ppma_author?post=3114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}